{"id":292,"date":"2025-03-04T15:56:31","date_gmt":"2025-03-04T14:56:31","guid":{"rendered":"https:\/\/casavinicolaciccariello.com\/?page_id=292"},"modified":"2025-03-04T15:56:33","modified_gmt":"2025-03-04T14:56:33","slug":"ein-wein-von-wert","status":"publish","type":"page","link":"https:\/\/casavinicolaciccariello.com\/de\/unternehmen\/ein-wein-von-wert\/","title":{"rendered":"Ein Wein von Wert"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":178,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-292","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un vino di valore | Casa Vinicola Ciccariello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casavinicolaciccariello.com\/de\/unternehmen\/ein-wein-von-wert\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un vino di valore | Casa Vinicola Ciccariello\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casavinicolaciccariello.com\/de\/unternehmen\/ein-wein-von-wert\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa Vinicola Ciccariello\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/casavinicolaciccariello\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-04T14:56:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casavinicolaciccariello.com\/wp-content\/uploads\/2025\/03\/logo1200px.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"343\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/casavinicolaciccariello.com\/azienda\/un-vino-di-valore\/\",\"url\":\"https:\/\/casavinicolaciccariello.com\/azienda\/un-vino-di-valore\/\",\"name\":\"Un vino di valore | Casa Vinicola Ciccariello\",\"isPartOf\":{\"@id\":\"https:\/\/casavinicolaciccariello.com\/#website\"},\"datePublished\":\"2025-03-04T14:56:31+00:00\",\"dateModified\":\"2025-03-04T14:56:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/casavinicolaciccariello.com\/azienda\/un-vino-di-valore\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/casavinicolaciccariello.com\/azienda\/un-vino-di-valore\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/casavinicolaciccariello.com\/azienda\/un-vino-di-valore\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/casavinicolaciccariello.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Azienda\",\"item\":\"https:\/\/casavinicolaciccariello.com\/azienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Un vino di valore\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/casavinicolaciccariello.com\/#website\",\"url\":\"https:\/\/casavinicolaciccariello.com\/\",\"name\":\"Casa Vinicola Ciccariello\",\"description\":\"Dal 1966, la tradizione in ogni sorso.\",\"publisher\":{\"@id\":\"https:\/\/casavinicolaciccariello.com\/#organization\"},\"alternateName\":\"Cavici\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/casavinicolaciccariello.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/casavinicolaciccariello.com\/#organization\",\"name\":\"Casa Vinicola Ciccariello\",\"alternateName\":\"CA.VI.CI SRL\",\"url\":\"https:\/\/casavinicolaciccariello.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/casavinicolaciccariello.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/casavinicolaciccariello.com\/wp-content\/uploads\/2025\/03\/logo1200px.png\",\"contentUrl\":\"https:\/\/casavinicolaciccariello.com\/wp-content\/uploads\/2025\/03\/logo1200px.png\",\"width\":1200,\"height\":343,\"caption\":\"Casa Vinicola Ciccariello\"},\"image\":{\"@id\":\"https:\/\/casavinicolaciccariello.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/casavinicolaciccariello\",\"https:\/\/www.instagram.com\/casa_vinicola_ciccariello\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un vino di valore | Casa Vinicola Ciccariello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casavinicolaciccariello.com\/de\/unternehmen\/ein-wein-von-wert\/","og_locale":"de_DE","og_type":"article","og_title":"Un vino di valore | Casa Vinicola Ciccariello","og_url":"https:\/\/casavinicolaciccariello.com\/de\/unternehmen\/ein-wein-von-wert\/","og_site_name":"Casa Vinicola Ciccariello","article_publisher":"https:\/\/www.facebook.com\/casavinicolaciccariello","article_modified_time":"2025-03-04T14:56:33+00:00","og_image":[{"width":1200,"height":343,"url":"https:\/\/casavinicolaciccariello.com\/wp-content\/uploads\/2025\/03\/logo1200px.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/casavinicolaciccariello.com\/azienda\/un-vino-di-valore\/","url":"https:\/\/casavinicolaciccariello.com\/azienda\/un-vino-di-valore\/","name":"Un vino di valore | Casa Vinicola Ciccariello","isPartOf":{"@id":"https:\/\/casavinicolaciccariello.com\/#website"},"datePublished":"2025-03-04T14:56:31+00:00","dateModified":"2025-03-04T14:56:33+00:00","breadcrumb":{"@id":"https:\/\/casavinicolaciccariello.com\/azienda\/un-vino-di-valore\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casavinicolaciccariello.com\/azienda\/un-vino-di-valore\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/casavinicolaciccariello.com\/azienda\/un-vino-di-valore\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casavinicolaciccariello.com\/"},{"@type":"ListItem","position":2,"name":"Azienda","item":"https:\/\/casavinicolaciccariello.com\/azienda\/"},{"@type":"ListItem","position":3,"name":"Un vino di valore"}]},{"@type":"WebSite","@id":"https:\/\/casavinicolaciccariello.com\/#website","url":"https:\/\/casavinicolaciccariello.com\/","name":"Casa Vinicola Ciccariello","description":"Dal 1966, la tradizione in ogni sorso.","publisher":{"@id":"https:\/\/casavinicolaciccariello.com\/#organization"},"alternateName":"Cavici","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casavinicolaciccariello.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/casavinicolaciccariello.com\/#organization","name":"Casa Vinicola Ciccariello","alternateName":"CA.VI.CI SRL","url":"https:\/\/casavinicolaciccariello.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/casavinicolaciccariello.com\/#\/schema\/logo\/image\/","url":"https:\/\/casavinicolaciccariello.com\/wp-content\/uploads\/2025\/03\/logo1200px.png","contentUrl":"https:\/\/casavinicolaciccariello.com\/wp-content\/uploads\/2025\/03\/logo1200px.png","width":1200,"height":343,"caption":"Casa Vinicola Ciccariello"},"image":{"@id":"https:\/\/casavinicolaciccariello.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/casavinicolaciccariello","https:\/\/www.instagram.com\/casa_vinicola_ciccariello\/"]}]}},"_links":{"self":[{"href":"https:\/\/casavinicolaciccariello.com\/de\/wp-json\/wp\/v2\/pages\/292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casavinicolaciccariello.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/casavinicolaciccariello.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/casavinicolaciccariello.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/casavinicolaciccariello.com\/de\/wp-json\/wp\/v2\/comments?post=292"}],"version-history":[{"count":1,"href":"https:\/\/casavinicolaciccariello.com\/de\/wp-json\/wp\/v2\/pages\/292\/revisions"}],"predecessor-version":[{"id":293,"href":"https:\/\/casavinicolaciccariello.com\/de\/wp-json\/wp\/v2\/pages\/292\/revisions\/293"}],"up":[{"embeddable":true,"href":"https:\/\/casavinicolaciccariello.com\/de\/wp-json\/wp\/v2\/pages\/178"}],"wp:attachment":[{"href":"https:\/\/casavinicolaciccariello.com\/de\/wp-json\/wp\/v2\/media?parent=292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}